{"id":49,"count":2,"description":"","link":"https:\/\/blogit.gradia.fi\/sisu\/tag\/nivelvaihe\/","name":"nivelvaihe","slug":"nivelvaihe","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>nivelvaihe arkistot - Opiskelija oman el\u00e4m\u00e4ns\u00e4 ohjaajana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogit.gradia.fi\/sisu\/tag\/nivelvaihe\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"nivelvaihe arkistot - Opiskelija oman el\u00e4m\u00e4ns\u00e4 ohjaajana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogit.gradia.fi\/sisu\/tag\/nivelvaihe\/\" \/>\n<meta property=\"og:site_name\" content=\"Opiskelija oman el\u00e4m\u00e4ns\u00e4 ohjaajana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogit.gradia.fi\\\/sisu\\\/tag\\\/nivelvaihe\\\/\",\"url\":\"https:\\\/\\\/blogit.gradia.fi\\\/sisu\\\/tag\\\/nivelvaihe\\\/\",\"name\":\"nivelvaihe arkistot - Opiskelija oman el\u00e4m\u00e4ns\u00e4 ohjaajana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogit.gradia.fi\\\/sisu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogit.gradia.fi\\\/sisu\\\/tag\\\/nivelvaihe\\\/#breadcrumb\"},\"inLanguage\":\"fi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogit.gradia.fi\\\/sisu\\\/tag\\\/nivelvaihe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/blogit.gradia.fi\\\/sisu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"nivelvaihe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogit.gradia.fi\\\/sisu\\\/#website\",\"url\":\"https:\\\/\\\/blogit.gradia.fi\\\/sisu\\\/\",\"name\":\"Opiskelija oman el\u00e4m\u00e4ns\u00e4 ohjaajana\",\"description\":\"SISU-hanke\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogit.gradia.fi\\\/sisu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"nivelvaihe arkistot - Opiskelija oman el\u00e4m\u00e4ns\u00e4 ohjaajana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogit.gradia.fi\/sisu\/tag\/nivelvaihe\/","og_locale":"fi_FI","og_type":"article","og_title":"nivelvaihe arkistot - Opiskelija oman el\u00e4m\u00e4ns\u00e4 ohjaajana","og_url":"https:\/\/blogit.gradia.fi\/sisu\/tag\/nivelvaihe\/","og_site_name":"Opiskelija oman el\u00e4m\u00e4ns\u00e4 ohjaajana","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogit.gradia.fi\/sisu\/tag\/nivelvaihe\/","url":"https:\/\/blogit.gradia.fi\/sisu\/tag\/nivelvaihe\/","name":"nivelvaihe arkistot - Opiskelija oman el\u00e4m\u00e4ns\u00e4 ohjaajana","isPartOf":{"@id":"https:\/\/blogit.gradia.fi\/sisu\/#website"},"breadcrumb":{"@id":"https:\/\/blogit.gradia.fi\/sisu\/tag\/nivelvaihe\/#breadcrumb"},"inLanguage":"fi"},{"@type":"BreadcrumbList","@id":"https:\/\/blogit.gradia.fi\/sisu\/tag\/nivelvaihe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/blogit.gradia.fi\/sisu\/"},{"@type":"ListItem","position":2,"name":"nivelvaihe"}]},{"@type":"WebSite","@id":"https:\/\/blogit.gradia.fi\/sisu\/#website","url":"https:\/\/blogit.gradia.fi\/sisu\/","name":"Opiskelija oman el\u00e4m\u00e4ns\u00e4 ohjaajana","description":"SISU-hanke","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogit.gradia.fi\/sisu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"}]}},"_links":{"self":[{"href":"https:\/\/blogit.gradia.fi\/sisu\/wp-json\/wp\/v2\/tags\/49","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogit.gradia.fi\/sisu\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogit.gradia.fi\/sisu\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogit.gradia.fi\/sisu\/wp-json\/wp\/v2\/posts?tags=49"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}