{"id":9,"count":25,"description":"","link":"https:\/\/blogit.gradia.fi\/parastaosaamista\/category\/tamk\/","name":"TAMK","slug":"tamk","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TAMK Archives - Parasta osaamista -verkostohanke - B\u00e4sta kunnande -n\u00e4tverksprojektet Blogisivusto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogit.gradia.fi\/parastaosaamista\/category\/tamk\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TAMK Archives - Parasta osaamista -verkostohanke - B\u00e4sta kunnande -n\u00e4tverksprojektet Blogisivusto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogit.gradia.fi\/parastaosaamista\/category\/tamk\/\" \/>\n<meta property=\"og:site_name\" content=\"Parasta osaamista -verkostohanke - B\u00e4sta kunnande -n\u00e4tverksprojektet Blogisivusto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogit.gradia.fi\\\/parastaosaamista\\\/category\\\/tamk\\\/\",\"url\":\"https:\\\/\\\/blogit.gradia.fi\\\/parastaosaamista\\\/category\\\/tamk\\\/\",\"name\":\"TAMK Archives - Parasta osaamista -verkostohanke - B\u00e4sta kunnande -n\u00e4tverksprojektet Blogisivusto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogit.gradia.fi\\\/parastaosaamista\\\/#website\"},\"inLanguage\":\"fi\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogit.gradia.fi\\\/parastaosaamista\\\/#website\",\"url\":\"https:\\\/\\\/blogit.gradia.fi\\\/parastaosaamista\\\/\",\"name\":\"Parasta osaamista -verkostohanke - B\u00e4sta kunnande -n\u00e4tverksprojektet Blogisivusto\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogit.gradia.fi\\\/parastaosaamista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TAMK Archives - Parasta osaamista -verkostohanke - B\u00e4sta kunnande -n\u00e4tverksprojektet Blogisivusto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogit.gradia.fi\/parastaosaamista\/category\/tamk\/","og_locale":"fi_FI","og_type":"article","og_title":"TAMK Archives - Parasta osaamista -verkostohanke - B\u00e4sta kunnande -n\u00e4tverksprojektet Blogisivusto","og_url":"https:\/\/blogit.gradia.fi\/parastaosaamista\/category\/tamk\/","og_site_name":"Parasta osaamista -verkostohanke - B\u00e4sta kunnande -n\u00e4tverksprojektet Blogisivusto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogit.gradia.fi\/parastaosaamista\/category\/tamk\/","url":"https:\/\/blogit.gradia.fi\/parastaosaamista\/category\/tamk\/","name":"TAMK Archives - Parasta osaamista -verkostohanke - B\u00e4sta kunnande -n\u00e4tverksprojektet Blogisivusto","isPartOf":{"@id":"https:\/\/blogit.gradia.fi\/parastaosaamista\/#website"},"inLanguage":"fi"},{"@type":"WebSite","@id":"https:\/\/blogit.gradia.fi\/parastaosaamista\/#website","url":"https:\/\/blogit.gradia.fi\/parastaosaamista\/","name":"Parasta osaamista -verkostohanke - B\u00e4sta kunnande -n\u00e4tverksprojektet Blogisivusto","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogit.gradia.fi\/parastaosaamista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"}]}},"_links":{"self":[{"href":"https:\/\/blogit.gradia.fi\/parastaosaamista\/wp-json\/wp\/v2\/categories\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogit.gradia.fi\/parastaosaamista\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogit.gradia.fi\/parastaosaamista\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blogit.gradia.fi\/parastaosaamista\/wp-json\/wp\/v2\/posts?categories=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}