{"id":17,"count":1,"description":"","link":"https:\/\/blogit.gradia.fi\/eoppimiskulttuuri\/tag\/onenote\/","name":"OneNote","slug":"onenote","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OneNote Archives - eOppimiskulttuuria kaikille<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogit.gradia.fi\/eoppimiskulttuuri\/tag\/onenote\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OneNote Archives - eOppimiskulttuuria kaikille\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogit.gradia.fi\/eoppimiskulttuuri\/tag\/onenote\/\" \/>\n<meta property=\"og:site_name\" content=\"eOppimiskulttuuria kaikille\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogit.gradia.fi\\\/eoppimiskulttuuri\\\/tag\\\/onenote\\\/\",\"url\":\"https:\\\/\\\/blogit.gradia.fi\\\/eoppimiskulttuuri\\\/tag\\\/onenote\\\/\",\"name\":\"OneNote Archives - eOppimiskulttuuria kaikille\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogit.gradia.fi\\\/eoppimiskulttuuri\\\/#website\"},\"inLanguage\":\"fi\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogit.gradia.fi\\\/eoppimiskulttuuri\\\/#website\",\"url\":\"https:\\\/\\\/blogit.gradia.fi\\\/eoppimiskulttuuri\\\/\",\"name\":\"eOppimiskulttuuria kaikille\",\"description\":\"Office365 -ymp\u00e4rist\u00f6n pedagoginen k\u00e4ytt\u00f6\u00f6notto ammatillisilla aloilla.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogit.gradia.fi\\\/eoppimiskulttuuri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OneNote Archives - eOppimiskulttuuria kaikille","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogit.gradia.fi\/eoppimiskulttuuri\/tag\/onenote\/","og_locale":"fi_FI","og_type":"article","og_title":"OneNote Archives - eOppimiskulttuuria kaikille","og_url":"https:\/\/blogit.gradia.fi\/eoppimiskulttuuri\/tag\/onenote\/","og_site_name":"eOppimiskulttuuria kaikille","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogit.gradia.fi\/eoppimiskulttuuri\/tag\/onenote\/","url":"https:\/\/blogit.gradia.fi\/eoppimiskulttuuri\/tag\/onenote\/","name":"OneNote Archives - eOppimiskulttuuria kaikille","isPartOf":{"@id":"https:\/\/blogit.gradia.fi\/eoppimiskulttuuri\/#website"},"inLanguage":"fi"},{"@type":"WebSite","@id":"https:\/\/blogit.gradia.fi\/eoppimiskulttuuri\/#website","url":"https:\/\/blogit.gradia.fi\/eoppimiskulttuuri\/","name":"eOppimiskulttuuria kaikille","description":"Office365 -ymp\u00e4rist\u00f6n pedagoginen k\u00e4ytt\u00f6\u00f6notto ammatillisilla aloilla.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogit.gradia.fi\/eoppimiskulttuuri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"}]}},"_links":{"self":[{"href":"https:\/\/blogit.gradia.fi\/eoppimiskulttuuri\/wp-json\/wp\/v2\/tags\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogit.gradia.fi\/eoppimiskulttuuri\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogit.gradia.fi\/eoppimiskulttuuri\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogit.gradia.fi\/eoppimiskulttuuri\/wp-json\/wp\/v2\/posts?tags=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}